{"id":2025,"date":"2022-10-14T16:22:28","date_gmt":"2022-10-14T14:22:28","guid":{"rendered":"https:\/\/laurencechevallier.com\/?post_type=product&#038;p=2025"},"modified":"2026-06-12T15:05:59","modified_gmt":"2026-06-12T13:05:59","slug":"callista-cha-cha-broche","status":"publish","type":"product","link":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/","title":{"rendered":"Callista Cha-Cha (Broch\u00e9)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Inclus :<br \/>\nUn magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts.<\/p>\n<p>Elle fait une fixette sur Dirty Dancing.<br \/>\nIl veut se venger de son ex-infid\u00e8le.<br \/>\nMon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater !<br \/>\nApparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer&#8230;<br \/>\nEh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu !<br \/>\nEn tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable.<br \/>\nJ\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e.<br \/>\nEt qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate !<\/p>\n<p>Une romance irr\u00e9v\u00e9rencieuse \u00e0 l&rsquo;humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)<\/p>","protected":false},"featured_media":2541,"template":"","meta":[],"product_brand":[117],"product_cat":[95,112,101],"product_tag":[],"class_list":["post-2025","product","type-product","status-publish","has-post-thumbnail","product_author-laurence-chevallier","product_brand-black-queen-editions","product_cat-broches","product_cat-comedie-romantique","product_cat-new-romance","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l&#039;humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Laurence Chevallier - J\u2019\u00e9cris des histoires d\u2019amour \u00e0 ma sauce\u2026 parfois sucr\u00e9e, parfois\u00a0piquante\u00a0\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier\" \/>\n\t\t<meta property=\"og:description\" content=\"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l&#039;humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-14T14:22:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-06-12T13:05:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l&#039;humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/laurencechevallier.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/produit-autrice\\\/laurence-chevallier\\\/#listItem\",\"name\":\"Laurence Chevallier\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/produit-autrice\\\/laurence-chevallier\\\/#listItem\",\"position\":3,\"name\":\"Laurence Chevallier\",\"item\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/produit-autrice\\\/laurence-chevallier\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#listItem\",\"name\":\"Callista Cha-Cha (Broch\\u00e9)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#listItem\",\"position\":4,\"name\":\"Callista Cha-Cha (Broch\\u00e9)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/produit-autrice\\\/laurence-chevallier\\\/#listItem\",\"name\":\"Laurence Chevallier\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#itempage\",\"url\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/\",\"name\":\"Callista Cha-Cha (Broch\\u00e9) - Laurence Chevallier\",\"description\":\"Inclus : Un magnet, une carte postale illustr\\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\\u00e8le. Mon mantra : ne surtout pas s\\u2019attacher, mais rien n\\u2019emp\\u00eache de s\\u2019\\u00e9clater ! Apparemment, ce n\\u2019est pas l\\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \\u00e7a coince d\\u00e8s le premier regard. Il est jeune, s\\u00e9duisant et ambitieux, mais n\\u2019a pas dig\\u00e9r\\u00e9 son divorce. Pour se venger de son ex, il s\\u2019inscrit \\u00e0 un concours de danse dans le but de la d\\u00e9fier. Il ne lui manque plus qu\\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\\u2019animatrice de la soir\\u00e9e de mariage de ma meilleure amie, j\\u2019avais d\\u00e9j\\u00e0 pr\\u00e9vu d\\u2019ex\\u00e9cuter le port\\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \\u00e0 ma flamboyante prestation ? Quand je d\\u00e9couvre que mon patron a des talents de danseur dignes d\\u2019une com\\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\\u00e9ticences \\u00e0 son \\u00e9gard et lui propose un deal improbable. J\\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\\u00e9e qui d\\u00e9passerait largement le cadre de notre partenariat \\u00e0 dur\\u00e9e d\\u00e9termin\\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\\u00eate ! Une romance irr\\u00e9v\\u00e9rencieuse \\u00e0 l'humour d\\u00e9capant, destin\\u00e9e \\u00e0 un public majeur et averti. (One shot ind\\u00e9pendant)\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/laurencechevallier.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/12.avif\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/product\\\/callista-cha-cha-broche\\\/#mainImage\"},\"datePublished\":\"2022-10-14T16:22:28+02:00\",\"dateModified\":\"2026-06-12T15:05:59+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/#organization\",\"name\":\"Laurence Chevallier\",\"description\":\"J\\u2019\\u00e9cris des histoires d\\u2019amour \\u00e0 ma sauce\\u2026 parfois sucr\\u00e9e, parfois\\u00a0piquante\\u00a0\",\"url\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/\",\"name\":\"Laurence Chevallier\",\"description\":\"J\\u2019\\u00e9cris des histoires d\\u2019amour \\u00e0 ma sauce\\u2026 parfois sucr\\u00e9e, parfois\\u00a0piquante\\u00a0\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/laurencechevallier.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier","description":"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l'humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)","canonical_url":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/laurencechevallier.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/laurencechevallier.com\/en\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/#listItem","name":"Laurence Chevallier"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/#listItem","position":3,"name":"Laurence Chevallier","item":"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/","nextItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#listItem","name":"Callista Cha-Cha (Broch\u00e9)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#listItem","position":4,"name":"Callista Cha-Cha (Broch\u00e9)","previousItem":{"@type":"ListItem","@id":"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/#listItem","name":"Laurence Chevallier"}}]},{"@type":"ItemPage","@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#itempage","url":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/","name":"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier","description":"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l'humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/laurencechevallier.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/laurencechevallier.com\/wp-content\/uploads\/2026\/01\/12.avif","@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/#mainImage"},"datePublished":"2022-10-14T16:22:28+02:00","dateModified":"2026-06-12T15:05:59+02:00"},{"@type":"Organization","@id":"https:\/\/laurencechevallier.com\/en\/#organization","name":"Laurence Chevallier","description":"J\u2019\u00e9cris des histoires d\u2019amour \u00e0 ma sauce\u2026 parfois sucr\u00e9e, parfois\u00a0piquante\u00a0","url":"https:\/\/laurencechevallier.com\/en\/"},{"@type":"WebSite","@id":"https:\/\/laurencechevallier.com\/en\/#website","url":"https:\/\/laurencechevallier.com\/en\/","name":"Laurence Chevallier","description":"J\u2019\u00e9cris des histoires d\u2019amour \u00e0 ma sauce\u2026 parfois sucr\u00e9e, parfois\u00a0piquante\u00a0","inLanguage":"en-US","publisher":{"@id":"https:\/\/laurencechevallier.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Laurence Chevallier - J\u2019\u00e9cris des histoires d\u2019amour \u00e0 ma sauce\u2026 parfois sucr\u00e9e, parfois\u00a0piquante\u00a0","og:type":"article","og:title":"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier","og:description":"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l'humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)","og:url":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/","article:published_time":"2022-10-14T14:22:28+00:00","article:modified_time":"2026-06-12T13:05:59+00:00","twitter:card":"summary_large_image","twitter:title":"Callista Cha-Cha (Broch\u00e9) - Laurence Chevallier","twitter:description":"Inclus : Un magnet, une carte postale illustr\u00e9e par Nicolas Jamonneau, et un marque page sont offerts. Elle fait une fixette sur Dirty Dancing. Il veut se venger de son ex-infid\u00e8le. Mon mantra : ne surtout pas s\u2019attacher, mais rien n\u2019emp\u00eache de s\u2019\u00e9clater ! Apparemment, ce n\u2019est pas l\u2019opinion de mon patron, Dan Vila-Wilson, avec qui \u00e7a coince d\u00e8s le premier regard. Il est jeune, s\u00e9duisant et ambitieux, mais n\u2019a pas dig\u00e9r\u00e9 son divorce. Pour se venger de son ex, il s\u2019inscrit \u00e0 un concours de danse dans le but de la d\u00e9fier. Il ne lui manque plus qu\u2019une charmante partenaire pour se lancer... Eh bien, fallait le dire plus t\u00f4t ! Je suis la femme parfaite pour ce genre de plan tordu ! En tant qu\u2019animatrice de la soir\u00e9e de mariage de ma meilleure amie, j\u2019avais d\u00e9j\u00e0 pr\u00e9vu d\u2019ex\u00e9cuter le port\u00e9 de Dirty Dancing, alors pourquoi ne pas ajouter un peu de drama \u00e0 ma flamboyante prestation ? Quand je d\u00e9couvre que mon patron a des talents de danseur dignes d\u2019une com\u00e9die musicale et un penchant pour le voyeurisme, je fais fi de mes r\u00e9ticences \u00e0 son \u00e9gard et lui propose un deal improbable. J\u2019ignorais que cet arrangement allait se transformer en une danse endiabl\u00e9e qui d\u00e9passerait largement le cadre de notre partenariat \u00e0 dur\u00e9e d\u00e9termin\u00e9e. Et qui pourrait bien me faire perdre le rythme, ou pire, la t\u00eate ! Une romance irr\u00e9v\u00e9rencieuse \u00e0 l'humour d\u00e9capant, destin\u00e9e \u00e0 un public majeur et averti. (One shot ind\u00e9pendant)"},"aioseo_meta_data":{"post_id":"2025","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-10 15:22:28","updated":"2026-06-12 16:27:19","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laurencechevallier.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laurencechevallier.com\/en\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/\" title=\"Laurence Chevallier\">Laurence Chevallier<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCallista Cha-Cha (Broch\u00e9)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/laurencechevallier.com\/en"},{"label":"Shop","link":"https:\/\/laurencechevallier.com\/en\/shop\/"},{"label":"Laurence Chevallier","link":"https:\/\/laurencechevallier.com\/en\/produit-autrice\/laurence-chevallier\/"},{"label":"Callista Cha-Cha (Broch\u00e9)","link":"https:\/\/laurencechevallier.com\/en\/product\/callista-cha-cha-broche\/"}],"_links":{"self":[{"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/product\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/media\/2541"}],"wp:attachment":[{"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/media?parent=2025"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/product_brand?post=2025"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/product_cat?post=2025"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/laurencechevallier.com\/en\/wp-json\/wp\/v2\/product_tag?post=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}